{"id":7221,"date":"2026-04-01T00:00:05","date_gmt":"2026-03-31T15:00:05","guid":{"rendered":"https:\/\/espguitars.co.jp\/crafthouse\/7221\/"},"modified":"2026-04-01T13:23:56","modified_gmt":"2026-04-01T04:23:56","slug":"%e3%82%b7%e3%83%a7%e3%83%83%e3%83%94%e3%83%b3%e3%82%b0%e3%82%af%e3%83%ac%e3%82%b8%e3%83%83%e3%83%88-%e6%9c%80%e5%a4%a748%e5%9b%9e%e6%89%95%e3%81%84%e3%81%be%e3%81%a7%e9%87%91%e5%88%a90%ef%bc%85-2","status":"publish","type":"post","link":"https:\/\/espguitars.co.jp\/crafthouse\/7221\/","title":{"rendered":"\u30b7\u30e7\u30c3\u30d4\u30f3\u30b0\u30af\u30ec\u30b8\u30c3\u30c8 \u6700\u592748\u56de\u6255\u3044\u307e\u3067\u91d1\u52290\uff05\uff01"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u671f\u9593\u9650\u5b9a\uff01\u30b7\u30e7\u30c3\u30d4\u30f3\u30b0\u30af\u30ec\u30b8\u30c3\u30c8\u3067\u306e\u304a\u8cb7\u3044\u7269\u304c\u304a\u5f97\u306b\u306a\u308b\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\u5b9f\u65bd\u4e2d\uff01<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7221","post","type-post","status-publish","format-standard","hentry","category-campaign"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 02:06:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/posts\/7221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/comments?post=7221"}],"version-history":[{"count":5,"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/posts\/7221\/revisions"}],"predecessor-version":[{"id":7506,"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/posts\/7221\/revisions\/7506"}],"wp:attachment":[{"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/media?parent=7221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/categories?post=7221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espguitars.co.jp\/crafthouse\/wp-json\/wp\/v2\/tags?post=7221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}